{"id":1133,"date":"2025-05-19T15:17:07","date_gmt":"2025-05-19T09:47:07","guid":{"rendered":"https:\/\/marketresearchcommunity.com\/?p=1133"},"modified":"2025-05-19T15:17:07","modified_gmt":"2025-05-19T09:47:07","slug":"fragrance-wax-melts-market","status":"publish","type":"post","link":"https:\/\/marketresearchcommunity.com\/mrc\/fr\/fragrance-wax-melts-market\/","title":{"rendered":"Analyse de la taille, de la part et des tendances du march\u00e9, par type de cire (par exemple, cire d&#8217;abeille, paraffine de paraffine et autres), type de fragrance (florale, fruit\u00e9e et autres), cha\u00eene de distribution (commerce en ligne, site Web de l&#8217;entreprise) et vente au d\u00e9tail hors ligne (march\u00e9 de d\u00e9tail\/supermarch\u00e9, magasins sp\u00e9cialis\u00e9s, etc.), demande (r\u00e9sidentiel et commercial), par r\u00e9gion, p\u00e9riode de pr\u00e9vision 2023-2030"},"content":{"rendered":"<h2><strong>March\u00e9 cl\u00e9 Aper\u00e7u:<\/strong><\/h2>\n<p><strong>M\u00e9lettes de cire de parfum La taille du march\u00e9 \u00e9quivalait \u00e0 1,92 milliard de dollars en 2022, soit une croissance du TCAC de 6,2 % au cours de la p\u00e9riode de pr\u00e9vision (2023-2030), et le march\u00e9 est estim\u00e9 \u00e0 3,3 milliards de dollars d&#8217;ici 2030<\/strong><strong>.<\/strong>Parfum <a href=\"https:\/\/marketresearchcommunity.com\/wax-market\/\">cire<\/a> Les fusions sont des morceaux de cire parfum\u00e9e souvent con\u00e7us dans de belles formes, couleurs et tailles. Ces <a href=\"https:\/\/marketresearchcommunity.com\/wax-melts-market\/\">cire fondue<\/a> sont fondus \u00e0 l&#8217;aide d&#8217;une source de chaleur, comme un r\u00e9chauffeur de cire, pour lib\u00e9rer leur parfum dans une pi\u00e8ce et sont souvent constitu\u00e9s de combinaison de cire et d&#8217;huile de parfum. De plus, les bougies de cire de parfum sont un substitut populaire aux bougies traditionnelles, offrant une facilit\u00e9 d&#8217;utilisation, pas de m\u00e8ches, et un ar\u00f4me durable. Cela en fait une option pratique et rentable pour les entreprises et les consommateurs qui recherchent une exp\u00e9rience de parfum fiable. De nombreux types de parfums sont disponibles, y compris floral, fruit\u00e9, \u00e9pic\u00e9, boulangerie, bois\u00e9, frais et autres.<\/p>\n<p>De nombreuses entreprises investissent dans le d\u00e9veloppement de nouvelles technologies de parfum qui offrent des exp\u00e9riences de parfum plus durables et plus intenses. Par exemple- En octobre 2022, une marque japonaise de parfum D2C Shefar a introduit une gamme de produits de bougie parfum\u00e9e. Cette gamme de produits comprend plusieurs parfums diff\u00e9rents, dont des parfums floral, fruit\u00e9 et bois\u00e9. Les bougies sont faites de mat\u00e9riaux naturels de haute qualit\u00e9 et sont con\u00e7ues pour cr\u00e9er une atmosph\u00e8re chaleureuse et relaxante dans n&#8217;importe quel espace. Sur le plan g\u00e9ographique, l&#8217;Asie-Pacifique devrait \u00eatre la r\u00e9gion qui conna\u00eet la croissance la plus rapide au cours de la p\u00e9riode de pr\u00e9vision en raison de la forte demande des consommateurs pour les produits de parfumage maison, y compris les fondus de cire de parfum. En outre, la mont\u00e9e de <a href=\"https:\/\/marketresearchcommunity.com\/commerce-e-commerce-march\u00e9\/\">e-commerce Dans la r\u00e9gion, il a \u00e9t\u00e9 plus facile pour les consommateurs d&#8217;acheter en ligne de la cire de parfum et d&#8217;autres produits de parfumage, contribuant ainsi \u00e0 la croissance du march\u00e9.<\/p>\n<h3><strong>Dynamique du march\u00e9: <\/strong><\/h3>\n<h4><strong>Conducteur : <\/strong><\/h4>\n<ul>\n<li>Les fondus de cire de parfum offrent un moyen facile et pratique d&#8217;offrir une atmosph\u00e8re agr\u00e9able et accueillante dans leur maison, ce qui entra\u00eene une popularit\u00e9 croissante des produits de parfumage maison. Ceci est \u00e0 l&#8217;origine de la croissance du march\u00e9 de la fusion de cire de parfum.<\/li>\n<li>Le march\u00e9 offre une grande vari\u00e9t\u00e9 de parfums, des parfums traditionnels floraux et fruit\u00e9s aux parfums plus uniques et complexes comme les \u00e9pices, boulangerie, et plus encore. Une telle vari\u00e9t\u00e9 fait appel aux consommateurs et stimule la demande de produits.<\/li>\n<li>Les bougies parfum\u00e9es sont un cadeau populaire pour diverses occasions telles que les anniversaires, les mariages, et d&#8217;autres en raison de leur capacit\u00e9 \u00e0 cr\u00e9er une atmosph\u00e8re relaxante et apaisante, leur bel emballage, et leur polyvalence en termes d&#8217;options de parfum. Ce sont l\u00e0 les facteurs cl\u00e9s de la croissance du segment.<\/li>\n<\/ul>\n<h4><strong>3.1.2 Retenue: <\/strong><\/h4>\n<p>La production et l&#8217;\u00e9limination de la cire de parfum fondue contribuent \u00e0 la pollution environnementale et aux pr\u00e9occupations de durabilit\u00e9. Utilisation de parfums synth\u00e9tiques contenant des substances nocives <a href=\"https:\/\/marketresearchcommunity.com\/chemical-distribution-market\/\">produits chimiques<\/a> a un impact n\u00e9gatif sur l&#8217;environnement et la sant\u00e9 humaine. En outre, l&#8217;emballage des produits, souvent en plastique, contribue \u00e0 l&#8217;accumulation de <a href=\"https:\/\/marketresearchcommunity.com\/waste-derived-bio-gas-market\/\">d\u00e9chets<\/a> et la pollution de l&#8217;environnement. Par cons\u00e9quent, ce souci de durabilit\u00e9 entrave la croissance du march\u00e9 \u00e0 mesure que les consommateurs deviennent plus conscious de l&#8217;impact environnemental de leurs d\u00e9cisions d&#8217;achat.<\/p>\n<h3><strong>Possibilit\u00e9s :<\/strong><\/h3>\n<p>Les consommateurs sont devenus plus conscients de l&#8217;environnement et de la sant\u00e9. On s&#8217;attend donc \u00e0 ce que le d\u00e9veloppement de cires de parfum \u00e9cologiques et durables qui r\u00e9pondent aux pr\u00e9occupations environnementales et en mati\u00e8re de durabilit\u00e9 offre de nombreuses possibilit\u00e9s aux principaux acteurs du march\u00e9. En outre, l&#8217;innovation dans la technologie des parfums, comme le d\u00e9veloppement de nouvelles formulations de parfums qui offrent une exp\u00e9rience de parfum plus durable et plus intense, qui est \u00e9galement pr\u00e9vue pour fournir une opportunit\u00e9 lucrative pour la croissance du march\u00e9.<\/p>\n<h3><strong>Couverture du rapport Fragrance Wax Melts :<\/strong><\/h3>\n<table>\n<tbody>\n<tr>\n<td width=\"295\"><strong>Attributs du rapport<\/strong><\/td>\n<td width=\"306\"><strong>D\u00e9tails du rapport<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"295\"><strong>\u00c9ch\u00e9ancier de l&#8217;\u00e9tude<\/strong><\/td>\n<td width=\"306\">2017-2030<\/td>\n<\/tr>\n<tr>\n<td width=\"295\"><strong>Taille du march\u00e9 en 2030 (milliard USD)<\/strong><\/td>\n<td width=\"306\">3.3 milliard<\/td>\n<\/tr>\n<tr>\n<td width=\"295\"><strong>TCAC (2022-2030)<\/strong><\/td>\n<td width=\"306\">6,2 %<\/td>\n<\/tr>\n<tr>\n<td width=\"295\"><strong>Par type de cire <\/strong><\/td>\n<td width=\"306\">Farine d&#8217;abeilles, paraffine de paraffine, paume de soja, cire de colza, cire de coco et autres<\/td>\n<\/tr>\n<tr>\n<td width=\"295\"><strong>Par type de parfum <\/strong><\/td>\n<td width=\"306\">Floral, fruit\u00e9, frais, lavande, sandale, vanille et autres<\/td>\n<\/tr>\n<tr>\n<td width=\"295\"><strong>Par canal de distribution <\/strong><\/td>\n<td width=\"306\">Commerce de d\u00e9tail en ligne (commerce \u00e9lectronique, site Web appartenant \u00e0 l&#8217;entreprise) et Commerce de d\u00e9tail hors ligne (Hypermarket\/Supermarket, magasins sp\u00e9cialis\u00e9s, magasins minist\u00e9riels, etc.)<\/td>\n<\/tr>\n<tr>\n<td width=\"295\"><strong>Par demande<\/strong><\/td>\n<td largeur=30<\/tr>\n<\/tbody>\n<\/table>\n<p>6&#8243;>R\u00e9sidents et commerciaux<\/p>\n<tr>\n<td width=\"295\"><strong>Par g\u00e9ographie<\/strong><\/td>\n<td width=\"306\">Am\u00e9rique du Nord, Europe, Asie-Pacifique, Am\u00e9rique latine, Moyen-Orient et Afrique<\/td>\n<\/tr>\n<tr>\n<td width=\"295\"><strong>Acteurs cl\u00e9s<\/strong><\/td>\n<td width=\"306\">Bath &#038; Body Works, LLC., Yankee Candle Company, Inc., SC Johnson &#038; Son, Inc., Scentsy, Inc., Goose Creek Candle Company, Candle-Lite Company, LLC, Happy Wax, Auro Decor Pvt. Ltd., Reckitt Benckiser Group PLC et Candles by Victoria<\/td>\n<\/tr>\n<h3><strong>Segmentation du march\u00e9:<\/strong><\/h3>\n<h4><strong>Par type de cire<\/strong><\/h4>\n<p>Le segment de type Wax est class\u00e9 en <a href=\"https:\/\/marketresearchcommunity.com\/beeswax-market\/\">cire d&#8217;abeille<\/a>, para-soy <a href=\"https:\/\/marketresearchcommunity.com\/paraffin-market\/\">Paraffine<\/a> des m\u00e9langes de cire, du palmier \u00e0 soja, de la cire de colza, de la cire de noix de coco et autres. Les paraffines para-soy\u00e9es ont repr\u00e9sent\u00e9 la plus grande part du march\u00e9 en 2022. Ceci est d\u00fb au fait que ces m\u00e9langes de cire offrent un bon \u00e9quilibre entre performance et co\u00fbt, les rendant populaires pour les consommateurs.<\/p>\n<p>Toutefois, le segment de la cire de soja devrait conna\u00eetre la croissance la plus rapide au cours de la p\u00e9riode de pr\u00e9vision. Cela est d\u00fb \u00e0 la demande croissante de produits naturels et <a href=\"https:\/\/marketresearchcommunity.com\/organic-and-natural-tampons-market\/\">biologique<\/a> produits, ainsi que les avantages pour l&#8217;environnement et la sant\u00e9 de la cire de soja. La cire de soja est d\u00e9riv\u00e9e du soja et est une ressource renouvelable biod\u00e9gradable et non toxique, faisant de la cire de soja une option attrayante pour les consommateurs qui recherchent des parfums \u00e9cologiques. Tous les facteurs susmentionn\u00e9s devraient \u00eatre \u00e0 l&#8217;origine de la demande pour le produit au cours de la p\u00e9riode de pr\u00e9vision.<\/p>\n<h4><strong>Par type de parfum<\/strong><\/h4>\n<p>ThLe segment de type de parfum est class\u00e9 en floral, fruit\u00e9, frais, lavande, santal, vanille et autres. Le segment floral a domin\u00e9 le march\u00e9 en termes de parts de revenus en 2022. Cela est d\u00fb \u00e0 la disponibilit\u00e9 de diff\u00e9rents parfums floraux tels que la rose, le jasmin et la lavande, qui sont populaires pour leurs parfums doux et rafra\u00eechissants.<\/p>\n<p>Cependant, le segment des parfums fruit\u00e9s devrait \u00eatre le segment qui conna\u00eet la croissance la plus rapide au cours de la p\u00e9riode de pr\u00e9vision. Ceci est attribu\u00e9 \u00e0 diff\u00e9rents types de parfums tels que les agrumes, les baies et les fruits tropicaux, qui deviennent de plus en plus populaires en raison de leurs parfums frais et revigorants. De plus, les consommateurs sont attir\u00e9s par les parfums fruit\u00e9s pour leur capacit\u00e9 \u00e0 cr\u00e9er une atmosph\u00e8re joyeuse et vivante dans la maison qui devrait augmenter la croissance de ce segment.<\/p>\n<h4><strong>Par canal de distribution<\/strong><\/h4>\n<p>Le segment des canaux de distribution est class\u00e9 dans le commerce de d\u00e9tail en ligne (<a href=\"https:\/\/marketresearchcommunity.com\/e-commerce-market\/\">commerce \u00e9lectronique<\/a>, site web appartenant \u00e0 l&#8217;entreprise) et de d\u00e9tail hors ligne (hypermarch\u00e9\/supermarch\u00e9, <a href=\"https:\/\/marketresearchcommunity.com\/specialty-chemicals-market\/\">sp\u00e9cialit\u00e9<\/a> les magasins, les magasins et autres). En 2022, le commerce de d\u00e9tail hors ligne repr\u00e9sentait la plus grande part du march\u00e9 de la cire de parfum. Ce segment comprend les magasins de briques et de briques comme les hypermarch\u00e9s, les supermarch\u00e9s, les magasins sp\u00e9cialis\u00e9s et les magasins minist\u00e9riels qui offrent aux clients la possibilit\u00e9 d&#8217;inspecter physiquement les produits et de choisir les parfums de leurs pr\u00e9f\u00e9rences. C&#8217;est le principal facteur de croissance du segment.<\/p>\n<p>De plus, on s&#8217;attend \u00e0 ce que le commerce de d\u00e9tail en ligne augmente le plus rapidement possible au cours de la p\u00e9riode de pr\u00e9vision. Ce segment comprend des plateformes de commerce \u00e9lectronique et des sites Web appartenant \u00e0 l&#8217;entreprise. La croissance de e-coL&#8217;utilisation croissante d&#8217;Internet pour faire du shopping facilite l&#8217;achat de cire de parfums par les consommateurs qui fondent dans le confort de leur propre maison. Cela devrait augmenter la port\u00e9e des entreprises de fusion de cire de parfum \u00e0 un large public. Ainsi, la croissance du segment devrait augmenter au cours de la p\u00e9riode de pr\u00e9vision.<\/p>\n<h4><strong>Par demande<\/strong><\/h4>\n<p>Le segment de demande est class\u00e9 comme r\u00e9sidentiel et commercial. Le segment des applications r\u00e9sidentielles repr\u00e9sentait la plus grande part du march\u00e9 en 2022. Ce segment comprend l&#8217;utilisation de cire de parfum fondue dans les maisons r\u00e9sidentielles pour cr\u00e9er une atmosph\u00e8re agr\u00e9able et masquer des odeurs d\u00e9sagr\u00e9ables. Tous ces facteurs stimulent la croissance du segment.<\/p>\n<p>Toutefois, le segment commercial devrait conna\u00eetre la croissance la plus rapide au cours de la p\u00e9riode de pr\u00e9vision. Ce segment comprend l&#8217;utilisation de cire de parfum fondus dans divers milieux tels que les spas, l&#8217;aromath\u00e9rapie, les studios de yoga, les salles de m\u00e9ditation et les bureaux pour promouvoir la relaxation et le soulagement du stress. Tous ces facteurs devraient stimuler la croissance du segment au cours de la p\u00e9riode de pr\u00e9vision. De plus, l&#8217;aromath\u00e9rapie devient de plus en plus populaire car plus de gens cherchent des moyens naturels et holistiques pour am\u00e9liorer leur bien-\u00eatre.<\/p>\n<h4><strong>Par r\u00e9gion<\/strong><\/h4>\n<p>Le segment r\u00e9gional comprend l&#8217;Asie-Pacifique, l&#8217;Europe, l&#8217;Am\u00e9rique du Nord, le Moyen-Orient et l&#8217;Afrique, l&#8217;Am\u00e9rique latine. L&#8217;Am\u00e9rique du Nord a repr\u00e9sent\u00e9 la plus grande part du march\u00e9 de la cire de parfum fondue en 2022. Ceci est attribu\u00e9 \u00e0 la pr\u00e9sence d&#8217;un grand nombre d&#8217;entreprises bien \u00e9tablies offrant une large gamme de produits de cire fondue comme Bath &#038; Body Works, LLC., Yankee Candle Company, Inc., SC Johnson &#038; Son, Inc. et d&#8217;autres. En outre, la r\u00e9gion a uneLes consommateurs cherchent de plus en plus des moyens d&#8217;am\u00e9liorer l&#8217;ambiance de leur foyer, ce qui stimule la demande de cire de parfum.<\/p>\n<p>En outre, l&#8217;Asie-Pacifique devrait \u00eatre la r\u00e9gion ayant connu la croissance la plus rapide du march\u00e9 au cours de la p\u00e9riode de pr\u00e9vision. Ceci est attribu\u00e9 \u00e0 la forte demande des consommateurs pour les produits de parfum \u00e0 la maison, en particulier la cire de parfum fond. De plus, les consommateurs d&#8217;Asie-Pacifique sont de plus en plus conscients des avantages de l&#8217;utilisation de la cire de parfum fondue, comme leur capacit\u00e9 \u00e0 cr\u00e9er une atmosph\u00e8re agr\u00e9able et \u00e0 masquer les odeurs d\u00e9sagr\u00e9ables. Cela devrait augmenter la demande de cire de parfum de haute qualit\u00e9 dans la r\u00e9gion.<\/p>\n<h3><strong>Le march\u00e9 de la cire de fragrance Melts Paysage concurrentiel : <\/strong><\/h3>\n<p>Les fondus de cire de parfum Le march\u00e9 est tr\u00e8s concurrentiel, plusieurs grands acteurs dominant le march\u00e9, ainsi que plusieurs petites entreprises. Ces entreprises investissent dans la recherche et le d\u00e9veloppement et augmentent leur capacit\u00e9 de production pour r\u00e9pondre \u00e0 la demande croissante de Fragrance Wax Melts. De plus, les fusions et acquisitions, les collaborations et les partenariats sont quelques-unes des strat\u00e9gies adopt\u00e9es par ces soci\u00e9t\u00e9s pour \u00e9tablir une forte assise sur le march\u00e9. Les principaux acteurs du march\u00e9 sont les suivants :<\/p>\n<ul>\n<li><a href=\"https:\/\/www.bathandbodyworks.com\/g\/home-fragrance\" rel=\"nofollow noopener\">Travaux de bain et de carrosserie, LLC.<\/a><\/li>\n<li><a href=\"https:\/\/www.yankeecandle.com\/yankee-candle\/home-fragrance\/wax-melts-warmers\/\" rel=\"nofollow noopener\">Yankee Candle Company, Inc.<\/a><\/li>\n<li><a href=\"https:\/\/www2.glade.com\/en-ca\/products\/candles\/wax-melts\" rel=\"nofollow noopener\">SC Johnson &#038; Son, Inc.<\/a><\/li>\n<li>Soci\u00e9t\u00e9 canadienne des postes<\/li>\n<li>Goose Creek Candle Company<\/li>\n<li>Candle-Lite Company, LLC<\/li>\n<li>Bonne cire<\/li>\n<li>Auro Decor Pvt. Ltd.<\/li>\n<li>Reckitt Benckiser Grou<\/li>\n<\/ul>\n<p>p PLC<\/p>\n<li>Bougies de Victoria<\/li>\n<h4><strong>Faits nouveaux :<\/strong><\/h4>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li>En octobre 2022- Une marque japonaise de parfum D2C Shefar a introduit une ligne de produits de bougie parfum\u00e9e. La ligne de bougies parfum\u00e9es Shefar comprend plusieurs options de parfum, y compris des parfums floral, fruit\u00e9 et bois\u00e9.<\/li>\n<li>En janvier 2022- La Yankee Candle Company, Inc., le fabricant mondial de parfums maison, a d\u00e9clar\u00e9 le lancement de sa nouvelle bougie Yankee appel\u00e9e Well Living Collection, une gamme de parfums inspir\u00e9s du bien-\u00eatre. La collection pr\u00e9sentait une gamme de parfums inspir\u00e9s du bien-\u00eatre qui visent \u00e0 cr\u00e9er une atmosph\u00e8re relaxante et rajeunissante pour les consommateurs.<\/li>\n<li>En juin 2021, la Candle-Lite Company (CBC) a d\u00e9clar\u00e9 son lancement officiel de bougies et de cires fondues, sous la marque Essential Elements. La nouvelle gamme de produits vise \u00e0 fournir aux consommateurs une exp\u00e9rience unique et holistique en combinant les avantages de l&#8217;aromath\u00e9rapie avec les avantages potentiels de la CBD.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/ul>\n<h2 id=\"toc\">Table of Content<\/h2>\n<p>To check our Table of Contents, please mail us at: <a href=\"mailto:sales@marketresearchcommunity.com\">sales@marketresearchcommunity.com<\/a><\/p>\n<h2 id=\"methodology\">Research Methodology<\/h2>\nThe Market Research Community offers numerous solutions and its full addition in the research methods to be skilled at each step. We use wide-ranging resources to produce the best outcome for our customers. The achievement of a research development is completely reliant on the research methods implemented by the company. We always faithful to our clients to find opportunities by examining the global market and offering economic insights.<br \/>\r\n<br \/>\r\nMarket Research Community are proud of our widespread coverage that encompasses the understanding of numerous major industry domains. Company offers consistency in our research report, we also offers on the part of the analysis of forecast across a range of coverage geographies and coverage. The research teams carry out primary and secondary research to carry out and design the data collection methods.\n","protected":false},"excerpt":{"rendered":"<p>March\u00e9 cl\u00e9 Aper\u00e7u: M\u00e9lettes de cire de parfum La taille du march\u00e9 \u00e9quivalait \u00e0 1,92 milliard de dollars en 2022, soit une croissance du TCAC de 6,2 % au cours de la p\u00e9riode de pr\u00e9vision (2023-2030), et le march\u00e9 est estim\u00e9 \u00e0 3,3 milliards de dollars d&#8217;ici 2030.Parfum cire Les fusions sont des morceaux de &hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[32],"tags":[],"class_list":["post-1133","post","type-post","status-publish","format-standard","hentry","category-petrochemicals"],"_links":{"self":[{"href":"https:\/\/marketresearchcommunity.com\/mrc\/fr\/wp-json\/wp\/v2\/posts\/1133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marketresearchcommunity.com\/mrc\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/marketresearchcommunity.com\/mrc\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/marketresearchcommunity.com\/mrc\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/marketresearchcommunity.com\/mrc\/fr\/wp-json\/wp\/v2\/comments?post=1133"}],"version-history":[{"count":0,"href":"https:\/\/marketresearchcommunity.com\/mrc\/fr\/wp-json\/wp\/v2\/posts\/1133\/revisions"}],"wp:attachment":[{"href":"https:\/\/marketresearchcommunity.com\/mrc\/fr\/wp-json\/wp\/v2\/media?parent=1133"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/marketresearchcommunity.com\/mrc\/fr\/wp-json\/wp\/v2\/categories?post=1133"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/marketresearchcommunity.com\/mrc\/fr\/wp-json\/wp\/v2\/tags?post=1133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}